{"id":780998,"date":"2023-10-06T07:52:52","date_gmt":"2023-10-06T06:52:52","guid":{"rendered":"https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1.png"},"modified":"2023-10-06T07:52:52","modified_gmt":"2023-10-06T06:52:52","slug":"5959201-128-1","status":"inherit","type":"attachment","link":"https:\/\/fitnfemale.com\/fr\/5959201-128-1\/","title":{"rendered":"5959201-128-1"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"slim_seo":{"title":"5959201-128-1 - FitNFemale\u00ae","description":""}},"class_list":["post-780998","attachment","type-attachment","status-inherit","hentry"],"_iconic_woothumbs_media":"","_iconic_woothumbs_media_aspect_ratio":"","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1.png'><img decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1.png\" class=\"attachment-medium size-medium\" alt=\"5959201 128\" srcset=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1.png 128w, https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1-100x100.png 100w, https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1-12x12.png 12w, https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1-120x120.png 120w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":128,"height":128,"file":"5959201-128-1.png","filesize":549,"sizes":{"woocommerce_gallery_thumbnail":{"file":"5959201-128-1-100x100.png","width":100,"height":100,"filesize":2157,"mime_type":"image\/png","source_url":"https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1.png"},"trp-custom-language-flag":{"file":"5959201-128-1-12x12.png","width":12,"height":12,"filesize":263,"mime_type":"image\/png","source_url":"https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1-12x12.png"},"yarpp-thumbnail":{"file":"5959201-128-1-120x120.png","width":120,"height":120,"filesize":2624,"mime_type":"image\/png","source_url":"https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1-120x120.png"},"full":{"file":"5959201-128-1.png","width":128,"height":128,"mime_type":"image\/png","source_url":"https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/fitnfemale.com\/wp-content\/uploads\/5959201-128-1.png","filename":"5959201-128-1.png","filesize":549,"_links":{"self":[{"href":"https:\/\/fitnfemale.com\/fr\/wp-json\/wp\/v2\/media\/780998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitnfemale.com\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/fitnfemale.com\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/fitnfemale.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fitnfemale.com\/fr\/wp-json\/wp\/v2\/comments?post=780998"}]}}