{"id":624653,"date":"2021-11-04T14:44:03","date_gmt":"2021-11-04T13:44:03","guid":{"rendered":"https:\/\/fitnfemale.com\/?page_id=624653"},"modified":"2021-11-24T09:28:15","modified_gmt":"2021-11-24T08:28:15","slug":"black-november-secret-deals","status":"publish","type":"page","link":"https:\/\/fitnfemale.com\/deu\/black-november-secret-deals\/","title":{"rendered":"Black November &#8211; Secret Deals"},"content":{"rendered":"<section class=\"section\" id=\"section_1181835294\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"effect-sliding-glass bg-effect fill no-click\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-1904613680\">\n\n\t<div id=\"col-775317369\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover has-video\" id=\"banner-1426306782\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                        \t<div class=\"video-overlay no-click fill visible\"><\/div>\n\t<video class=\"video-bg fill visible\" preload playsinline autoplay muted loop>\n\t\t<source src=\"\/\/dl.dropboxusercontent.com\/s\/f51tpr8oq5hl1x8\/black-november-secret-deals-post.mp4?raw=1\" type=\"video\/mp4\">\t<\/video>\n                        \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1426306782 {\n  padding-top: 99.99%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1181835294 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(0,0,0);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row align-equal align-center row-box-shadow-2\"  id=\"row-266574984\">\n\n\t<div id=\"col-426172156\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(0, 0, 0);\" >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center; color: #fff;\">Limited Black Friday Sets \u2605<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-266574984 > .col > .col-inner {\n  padding: 20px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t\n  \n    <div class=\"row  equalize-box large-columns-4 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n<div class=\"callout badge badge-circle\"><div class=\"badge-inner secondary on-sale\"><span class=\"onsale\">%<\/span><\/div><\/div>\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-vertical box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fitnfemale.com\/deu\/produkt\/glow-trio\/\" aria-label=\"Glow Trio\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/collagen-trio-2-247x296.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Collagen trio\" aria-hidden=\"true\" \/><img decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/collagen-trio-shop-247x296.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Collagen trio shop\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\"><p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/fitnfemale.com\/deu\/produkt\/glow-trio\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Glow Trio<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>\u00a087.70<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">inkl. MWST<\/small><\/del>&nbsp;<ins><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>\u00a074.55<\/bdi><\/span><\/ins> <small class=\"woocommerce-price-suffix\">inkl. MWST<\/small><\/span>\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\t\n  \n    <div class=\"row  equalize-box large-columns-4 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n<div class=\"callout badge badge-circle\"><div class=\"badge-inner secondary on-sale\"><span class=\"onsale\">%<\/span><\/div><\/div>\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-vertical box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fitnfemale.com\/deu\/produkt\/premium-fatburn-kombi\/\" aria-label=\"Shape and Burn Set\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/shapeandburnset-closeup8-247x296.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Shapeandburnset closeup8\" aria-hidden=\"true\" \/><img decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/shapeandburn-bundle-1-247x296.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Shapeandburn bundle (1)\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\"><p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/fitnfemale.com\/deu\/produkt\/premium-fatburn-kombi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Shape and Burn Set<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>\u00a0114.50<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">inkl. MWST<\/small><\/del>&nbsp;<ins><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>\u00a097.33<\/bdi><\/span><\/ins> <small class=\"woocommerce-price-suffix\">inkl. MWST<\/small><\/span>\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n<div class=\"callout badge badge-circle\"><div class=\"badge-inner secondary on-sale\"><span class=\"onsale\">%<\/span><\/div><\/div>\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-vertical box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fitnfemale.com\/deu\/produkt\/fit-strong-kombi\/\" aria-label=\"Fit &amp; Strong Workout\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/fit-strong-bundle-3-247x296.webp\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Fit strong bundle\" aria-hidden=\"true\" \/><img decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/fitstrongbundle1-1-247x296.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Fitstrongbundle1 (1)\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\"><p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/fitnfemale.com\/deu\/produkt\/fit-strong-kombi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Fit &amp; Strong Workout<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>\u00a085.60<\/bdi><\/span> <small class=\"woocommerce-price-suffix\">inkl. MWST<\/small><\/del>&nbsp;<ins><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>\u00a072.76<\/bdi><\/span><\/ins> <small class=\"woocommerce-price-suffix\">inkl. MWST<\/small><\/span>\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\n\t<section class=\"section\" id=\"section_863974594\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"effect-sliding-glass bg-effect fill no-click\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-small\"  id=\"row-805118257\">\n\n\t<div id=\"col-1868509485\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1892124852\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-800x800.jpg\" class=\"attachment-large size-large\" alt=\"Black november3\" srcset=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-800x800.jpg 800w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-200x200.jpg 200w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3.jpg 1000w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-400x400.jpg 400w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-280x280.jpg 280w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-768x768.jpg 768w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-12x12.jpg 12w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-130x130.jpg 130w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-510x510.jpg 510w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november3-150x150.jpg 150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1892124852 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/deu\/cart\/?apply_coupon=BL40\" class=\"button primary expand\" >\n\t\t<span>Gutschein hinzuf\u00fcgen<\/span>\n\t<i class=\"icon-plus\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2056061423\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1110368198\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-800x800.jpg\" class=\"attachment-large size-large\" alt=\"Black november1\" srcset=\"https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-800x800.jpg 800w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-200x200.jpg 200w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1.jpg 1000w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-400x400.jpg 400w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-280x280.jpg 280w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-768x768.jpg 768w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-12x12.jpg 12w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-130x130.jpg 130w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-510x510.jpg 510w, https:\/\/fitnfemale.com\/wp-content\/uploads\/black-november1-150x150.jpg 150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1110368198 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/deu\/cart\/?apply_coupon=B2G3\" class=\"button primary expand\" >\n\t\t<span>Gutschein hinzuf\u00fcgen<\/span>\n\t<i class=\"icon-plus\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_863974594 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(253, 175, 214);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-1849351357\">\n\n\t<div id=\"col-314408599\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<table class=\"product-trust\">\r\n<tbody>\r\n<tr>\r\n<td style=\"padding-left: 5px; line-height: 19px;\" valign=\"top\">\r\n<div><i class=\"fa fa-rocket\"><\/i>&nbsp;24h-Versand&nbsp;mit&nbsp;Tracking <\/div>\r\n<div><i class=\"fas fa-undo\"> <\/i> 14 Tage R\u00fcckgaberecht<\/div><\/td>\r\n<td style=\"padding-left: 5px; line-height: 19px;\" valign=\"top\">\r\n\r\n<div><i class=\"fa fa-check\"> <\/i> Rechnung<\/div>\r\n<div><i class=\"fas fa-truck\"><\/i> Portofrei ab 60 \u20ac mit DHL<\/div>\r\n\r\n<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"slim_seo":{"facebook_image":"https:\/\/fitnfemale.com\/wp-content\/uploads\/linkbl.jpg","title":"Reset your Body - FitNFemale\u00ae","description":"Bist du bereit f\u00fcr einen Reset? Reset your Body\u00a0 besteht aus 6 hochwertigen Produkten, einen Einnahmeplan, einer Einkaufliste sowie wichtigen Informationen zum"},"footnotes":""},"class_list":["post-624653","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fitnfemale.com\/deu\/wp-json\/wp\/v2\/pages\/624653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fitnfemale.com\/deu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fitnfemale.com\/deu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fitnfemale.com\/deu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fitnfemale.com\/deu\/wp-json\/wp\/v2\/comments?post=624653"}],"version-history":[{"count":0,"href":"https:\/\/fitnfemale.com\/deu\/wp-json\/wp\/v2\/pages\/624653\/revisions"}],"wp:attachment":[{"href":"https:\/\/fitnfemale.com\/deu\/wp-json\/wp\/v2\/media?parent=624653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}